{"id":4492,"date":"2024-11-21T19:32:41","date_gmt":"2024-11-21T23:32:41","guid":{"rendered":"https:\/\/mayralapaz.com\/?p=4492"},"modified":"2024-11-21T19:32:44","modified_gmt":"2024-11-21T23:32:44","slug":"margarita-parra-velazco-abanderada-de-las-raices-hispanas","status":"publish","type":"post","link":"https:\/\/mayralapaz.com\/index.php\/2024\/11\/21\/margarita-parra-velazco-abanderada-de-las-raices-hispanas\/","title":{"rendered":"Margarita Parra Velazco, Abanderada de las ra\u00edces hispanas"},"content":{"rendered":"\n<p><strong>Por Mayra La Paz\/PL<\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cuando se habla de mantener las ra\u00edces culturales que identifican a un ser humano en Estados Unidos, hay que hablar de Margarita Parra Velazco, una colombiana preocupada por no dejar morir el idioma espa\u00f1ol en los ni\u00f1os de origen hispano en Florida Central.<\/p>\n\n\n\n<p>Su trabajo de mas de mas de ocho a\u00f1os en la comunidad latina, la ha destacado entre las personalidades hispana de mayor relevancia en la comunidad. Entiende que ha impacta a la comunidad desde donde sirve, su organizaci\u00f3n sin fines de lucro, Ser Colombia, fundada 2014 con el prop\u00f3sito de brindar apoyo a la comunidad tanto colombiana como latina en el \u00e1rea de Orlando, para que no sufran las mimas situaciones complicadas por la que pasamos con mi familia al llegar a este pa\u00eds, indica a Portada Latina.<\/p>\n\n\n\n<p><strong>\u00a8Nosotros realizamos actividades educativas en espa\u00f1ol para los ni\u00f1os y eso le llega a familias interesadas en que sus hijos no pierdan la conexi\u00f3n con sus ra\u00edces, lo cual ayuda a que el ni\u00f1o adem\u00e1s de que conserve su identidad, mejore su nivel de espa\u00f1ol, lo que definitivamente redundar\u00e1 en beneficio no solo financiero a trav\u00e9s de su vida como profesional biling\u00fce, sino a nivel de interacci\u00f3n con otras culturas\u00a8, Manifiesta la Presidenta de Ser Colombia, Margarita Parra Velazco.<\/strong><\/p>\n\n\n\n<p><strong>-Que te llevo a convertirte en promotora del idioma espa\u00f1ol y mantener las culturas en las generaciones de ni\u00f1os nacidos ac\u00e1 en Estados Unidos.<\/strong><\/p>\n\n\n\n<p>\u00a8Durante mi vida, he tenido la oportunidad de vivir en diferentes pa\u00edses como Espa\u00f1a, Venezuela, Per\u00fa, y ahora en USA y en todos ellos, notaba que las familias colombianas siempre estaban preocupadas porque sus ni\u00f1os no pierdan su identidad cultural y procuraban buscar centros educativos o academias donde sus hijos pudieran estar en contacto con su folclore. Ac\u00e1 en Orlando hace 8 a\u00f1os, no hab\u00eda una entidad que brindara la oportunidad de que los ni\u00f1os se conectaran con sus ra\u00edces y, sobre todo, que aprendan y practiquen el idioma espa\u00f1ol. El comprobar que los ni\u00f1os de primera generaci\u00f3n o los que llegan a este pa\u00eds, dejan de hablar espa\u00f1ol, me llevo a crear Ser Colombia, con el prop\u00f3sito y la misi\u00f3n de fomentar en los ni\u00f1os, a trav\u00e9s del idioma espa\u00f1ol, nuestra cultura y tradiciones\u00a8.<\/p>\n\n\n\n<p><strong>\u2013 Cu\u00e1l es la mayor satisfacci\u00f3n que entiendes tener como profesional?<\/strong><\/p>\n\n\n\n<p>Profesionalmente, me he desarrollado en el campo de los bienes ra\u00edces, en el que llevo 20 a\u00f1os ayudando a trav\u00e9s de la educaci\u00f3n a los compradores hispanos. Mi mayor satisfacci\u00f3n es ver las caras de felicidad cuando mis clientes salen del cierre con las llaves de su nueva casa en la mano. A nivel comunitario, mi mayor satisfacci\u00f3n ha sido lograr crear una organizaci\u00f3n que aglutine a otras culturas y haber conseguido becas educativas para las madres cabeza de familia de Alianza Latina.<\/p>\n\n\n\n<p><strong>\u2013 Otros servicios que ofrecen<\/strong><\/p>\n\n\n\n<p>Ser Colombia, tiene como misi\u00f3n el servir de puente entre las familias que llegan o viven en la ciudad y entidades p\u00fablicas o privadas que ofrezcan informaci\u00f3n \u00fatil, eficiente y confiables. Para ello, desarrollamos talleres educativos con temas de inmigraci\u00f3n, taxes, seguridad cibern\u00e9tica, elaboraci\u00f3n de curriculum al estilo americano, temas de salud entre otros.<\/p>\n\n\n\n<p>Adicionalmente, a las clases para los ni\u00f1os y los talleres para los adultos, apoyamos a nuestros artistas en sus diferentes \u00e1reas, promoviendo sus presentaciones o invit\u00e1ndolos a nuestros eventos.<\/p>\n\n\n\n<p>A nivel comunitario, desde Hace 6 a\u00f1os, invite a otras organizaciones sin \u00e1nimo de lucro latinas, para que cre\u00e1ramos la organizaci\u00f3n&nbsp;<strong>\u201cALIANZA LATINA\u201d<\/strong>&nbsp;con la que se festeja y honra a las madres cabeza de familia latina. Elegimos una o dos madres de cada pa\u00eds participante y les hacemos un reconocimiento p\u00fablico durante un evento cultural. Este a\u00f1o adicionalmente al evento, les consegu\u00ed becas para que aprendan ingl\u00e9s, con un programa de las&nbsp;<strong>UCF GLOBAL,<\/strong>&nbsp;nos donaron 5 becas al 100%; con B English, una compa\u00f1\u00eda colombiana, consegu\u00ed que nos dieran una beca al 100% y 15% de descuentos para otras madres que quisieran aprender ingl\u00e9s.<\/p>\n\n\n\n<p>Con la Universidad Ana G. M\u00e9ndez, logre\u00e9 que nos dieran un descuento del 15% por cr\u00e9dito para las madres que quieran estudiar alguna carrera en ese prestigioso centro educativo. Con la organizaci\u00f3n Emprende Mujer Latina, consegu\u00ed que nos donaran 3 becas para madres emprendedoras, para que participaran su programa excelente programa educativo para mujeres emprendedoras, el cual estoy tomando para aplicarlo en el desarrollo de las organizaciones que dirijo.&nbsp; Creo realmente, esta es la mejor manera de ayudarlas para que puedan seguir adelante en su desarrollo profesional. Este ha sido sin lugar a duda el logro que m\u00e1s satisfacci\u00f3n me ha dado. El poder br\u00edndales a estas madres oportunidades educativas<\/p>\n\n\n\n<p><strong>-T\u00fa mensaje a la mujer de hoy, \u00bfcu\u00e1l es?<\/strong><\/p>\n\n\n\n<p>La mujer de hoy me refiero a las mujeres entre los 20 a los 45 a\u00f1os, no tiene nada que ver con lo que fueron nuestras madres, porque el ritmo de vida y la sociedad les exige desarrollar otros roles. Ya no son solo madres. Hoy la mujer desarrolla roles como profesional, como esposa, como madre, pero al mismo tiempo, sigue siendo hija.&nbsp; Mi mensaje para estas maravillosas mujeres es, que antes de pensar en todos esos roles, piensen en ellas. En su yo interior, en que es lo que ella, como ser humano, desea o necesita. Que no deje de quererse y preocuparse de su salud f\u00edsica y mental. Que piense en ella sin dejar sus dem\u00e1s roles.<\/p>\n\n\n\n<p><strong>Algo m\u00e1s sobre Margarita Parra Velazco<\/strong><\/p>\n\n\n\n<p>Margarita Parra, nace y se educa en Bogot\u00e1 Colombia. Se gradu\u00f3 como dibujante de arquitectura del colegio Mayor de Cundinamarca, estudio derecho en la Universidad Gran Colombia y en la universidad Central de Barcelona. Ha vivido en diferentes pa\u00edses como Espa\u00f1a, Per\u00fa, Venezuela y desde hace 25 a\u00f1os vive en los Estados unidos, donde obtuvo la licencia de Real Estate, profesi\u00f3n que ha desarrollado por 20 a\u00f1os. Ha obtenido varias designaciones para brindar un mejor servicio a sus clientes.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"Por Mayra La Paz\/PL &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cuando se habla de mantener las ra\u00edces culturales que identifican a un ser humano en Estados Unidos, hay que hablar de Margarita Parra Velazco, una colombiana preocupada por no dejar morir el idioma espa\u00f1ol en los ni\u00f1os de origen hispano en Florida Central. Su trabajo de mas de mas de [&hellip;]","protected":false},"author":6,"featured_media":4493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"series":[],"class_list":["post-4492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valor-latino"],"blocksy_meta":[],"episode_featured_image":"https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1.png","episode_player_image":"https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"light","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/mayralapaz.com\/feed\/podcast\/mayra-la-paz","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"Vm8xhDUakQ\"><a href=\"https:\/\/mayralapaz.com\/index.php\/2024\/11\/21\/margarita-parra-velazco-abanderada-de-las-raices-hispanas\/\">Margarita Parra Velazco, Abanderada de las ra\u00edces hispanas<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/mayralapaz.com\/index.php\/2024\/11\/21\/margarita-parra-velazco-abanderada-de-las-raices-hispanas\/embed\/#?secret=Vm8xhDUakQ\" width=\"500\" height=\"350\" title=\"\u00abMargarita Parra Velazco, Abanderada de las ra\u00edces hispanas\u00bb \u2014 Mayra La Paz\" data-secret=\"Vm8xhDUakQ\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n<\/script>\n"},"uagb_featured_image_src":{"full":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1.png",835,1200,false],"thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1-250x250.png",250,250,true],"medium":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1-209x300.png",209,300,true],"medium_large":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1-768x1104.png",768,1104,true],"large":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1-713x1024.png",713,1024,true],"1536x1536":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1.png",835,1200,false],"2048x2048":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1.png",835,1200,false],"woocommerce_archive_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1-500x500.png",500,500,true],"woocommerce_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1-300x300.png",300,300,true],"woocommerce_single":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1-600x862.png",600,862,true],"woocommerce_gallery_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/11\/Margarita-Parra-Velazco-980x1409-1-100x100.png",100,100,true]},"uagb_author_info":{"display_name":"Por la Redacci\u00f3n","author_link":"https:\/\/mayralapaz.com\/index.php\/author\/mayra\/"},"uagb_comment_info":0,"uagb_excerpt":"Por Mayra La Paz\/PL &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cuando se habla de mantener las ra\u00edces culturales que identifican a un ser humano en Estados Unidos, hay que hablar de Margarita Parra Velazco, una colombiana preocupada por no dejar morir el idioma espa\u00f1ol en los ni\u00f1os de origen hispano en Florida Central. Su trabajo de mas de mas de&hellip;","_links":{"self":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/comments?post=4492"}],"version-history":[{"count":1,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4492\/revisions"}],"predecessor-version":[{"id":4494,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4492\/revisions\/4494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/media\/4493"}],"wp:attachment":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/media?parent=4492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/categories?post=4492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/tags?post=4492"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/series?post=4492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}