{"id":4175,"date":"2024-10-18T14:38:30","date_gmt":"2024-10-18T18:38:30","guid":{"rendered":"https:\/\/mayralapaz.com\/?p=4175"},"modified":"2024-10-18T14:38:32","modified_gmt":"2024-10-18T18:38:32","slug":"rd-se-encamina-hacia-11-millones-de-turistas-en-2024-anuncian-cifra-record-de-4-18-millones-de-visitantes-en-los-primeros-4-meses","status":"publish","type":"post","link":"https:\/\/mayralapaz.com\/index.php\/2024\/10\/18\/rd-se-encamina-hacia-11-millones-de-turistas-en-2024-anuncian-cifra-record-de-4-18-millones-de-visitantes-en-los-primeros-4-meses\/","title":{"rendered":"RD se encamina hacia 11 millones de turistas en 2024: Anuncian cifra r\u00e9cord de 4.18 millones de visitantes en los primeros 4 meses"},"content":{"rendered":"\n<p>El turismo dominicano contin\u00faa con su&nbsp;<strong>crecimiento,<\/strong>&nbsp;al alcanzar la hist\u00f3rica cifra de&nbsp;<strong>4,178,683 visitantes<\/strong>&nbsp;en los primeros 4 meses del a\u00f1o, lo que proyecta que este&nbsp;<strong>2024<\/strong>&nbsp;se supere la llegada de&nbsp;<strong>m\u00e1s de 11 millones de visitantes<\/strong>.<\/p>\n\n\n\n<p>As\u00ed lo inform\u00f3 este lunes el ministro de Turismo,&nbsp;<strong>David Collado<\/strong>, en su habitual&nbsp;<strong>conferencia de prensa<\/strong>, donde da a conocer el comportamiento de la industria, en un encuentro efectuado en un hotel de la capital dominicana.<\/p>\n\n\n\n<p>El funcionario dijo que en los meses&nbsp;<strong>enero-abril<\/strong>&nbsp;el pa\u00eds recibi\u00f3&nbsp;<strong>3,039,302 turistas<\/strong>&nbsp;por la&nbsp;<strong>v\u00eda a\u00e9rea<\/strong>, lo que representa un&nbsp;<strong>crecimiento un 10 %,<\/strong>&nbsp;en relaci\u00f3n con el mismo per\u00edodo del 2023, 24 % respecto al 2019 y un 30 % en comparaci\u00f3n al 2018.<\/p>\n\n\n\n<p>Respecto a los&nbsp;<strong>cruceristas<\/strong>, Collado inform\u00f3 que en los primeros 4 meses de este a\u00f1o el pa\u00eds recibi\u00f3&nbsp;<strong>1,139,381 visitantes<\/strong>&nbsp;por la v\u00eda mar\u00edtima,&nbsp; lo que representa un&nbsp;<strong>incremento de 15 %&nbsp;<\/strong>respecto al 2023, 173 % con relaci\u00f3n al 2022 y un 234 % frente al 2019.<\/p>\n\n\n\n<p><em>\u00abEsas llegadas nos dan el gran n\u00famero, 4,178,683 visitantes en los primeros cuatro meses de este a\u00f1o; otro r\u00e9cord m\u00e1s\u00bb,<\/em>&nbsp;manifest\u00f3 el ministro de Turismo.<\/p>\n\n\n\n<p>La llegada de&nbsp;<strong>4,178,683 visitantes<\/strong>&nbsp;representa un&nbsp;<strong>crecimiento de un 12 %<\/strong>&nbsp;respecto al mismo per\u00edodo del 2023, 52% frente al 2022 y 43% con relaci\u00f3n al 2019.<\/p>\n\n\n\n<p>Indic\u00f3 que&nbsp;<strong>solo en abril<\/strong>&nbsp;el pa\u00eds recibi\u00f3&nbsp;<strong>704,740 turistas, v\u00eda a\u00e9rea<\/strong>, lo que representa un&nbsp;<strong>crecimiento de 3 %,<\/strong>&nbsp;en relaci\u00f3n con el mismo mes del 2023, 12 % respecto 2022 y un 20 % frente al 2019.<\/p>\n\n\n\n<p>En abril la llegada de cruceristas fue de&nbsp;<strong>248,459<\/strong>, lo que significa un crecimiento de un&nbsp;<strong>37 %<\/strong>&nbsp;respecto al mismo mes del 2023, 175 % frente al 2022 y un 234 % con respecto al 2019, manifest\u00f3 el funcionario.<\/p>\n\n\n\n<p>Los tres pa\u00edses que m\u00e1s visitantes aportaron en el mes de abril fueron&nbsp;<strong>Estados Unidos<\/strong>&nbsp;con un 53%,&nbsp;<strong>Canad\u00e1<\/strong>&nbsp;con 18% y&nbsp;<strong>Colombia<\/strong>&nbsp;con un 3%.<\/p>\n","protected":false},"excerpt":{"rendered":"El turismo dominicano contin\u00faa con su&nbsp;crecimiento,&nbsp;al alcanzar la hist\u00f3rica cifra de&nbsp;4,178,683 visitantes&nbsp;en los primeros 4 meses del a\u00f1o, lo que proyecta que este&nbsp;2024&nbsp;se supere la llegada de&nbsp;m\u00e1s de 11 millones de visitantes. As\u00ed lo inform\u00f3 este lunes el ministro de Turismo,&nbsp;David Collado, en su habitual&nbsp;conferencia de prensa, donde da a conocer el comportamiento de la [&hellip;]","protected":false},"author":6,"featured_media":4176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","_joinchat":[],"footnotes":""},"categories":[35],"tags":[],"series":[],"class_list":["post-4175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa-rd"],"blocksy_meta":[],"episode_featured_image":"https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1.jpg","episode_player_image":"https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"light","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/mayralapaz.com\/feed\/podcast\/mayra-la-paz","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"LV4HVQl71T\"><a href=\"https:\/\/mayralapaz.com\/index.php\/2024\/10\/18\/rd-se-encamina-hacia-11-millones-de-turistas-en-2024-anuncian-cifra-record-de-4-18-millones-de-visitantes-en-los-primeros-4-meses\/\">RD se encamina hacia 11 millones de turistas en 2024: Anuncian cifra r\u00e9cord de 4.18 millones de visitantes en los primeros 4 meses<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/mayralapaz.com\/index.php\/2024\/10\/18\/rd-se-encamina-hacia-11-millones-de-turistas-en-2024-anuncian-cifra-record-de-4-18-millones-de-visitantes-en-los-primeros-4-meses\/embed\/#?secret=LV4HVQl71T\" width=\"500\" height=\"350\" title=\"\u00abRD se encamina hacia 11 millones de turistas en 2024: Anuncian cifra r\u00e9cord de 4.18 millones de visitantes en los primeros 4 meses\u00bb \u2014 Mayra La Paz\" data-secret=\"LV4HVQl71T\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n<\/script>\n"},"uagb_featured_image_src":{"full":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1.jpg",1300,731,false],"thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1-250x250.jpg",250,250,true],"medium":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1-300x169.jpg",300,169,true],"medium_large":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1-768x432.jpg",768,432,true],"large":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1.jpg",1300,731,false],"2048x2048":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1.jpg",1300,731,false],"woocommerce_archive_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1-500x500.jpg",500,500,true],"woocommerce_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1-600x337.jpg",600,337,true],"woocommerce_gallery_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/Abril-2024-1-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"Por la Redacci\u00f3n","author_link":"https:\/\/mayralapaz.com\/index.php\/author\/mayra\/"},"uagb_comment_info":1,"uagb_excerpt":"El turismo dominicano contin\u00faa con su&nbsp;crecimiento,&nbsp;al alcanzar la hist\u00f3rica cifra de&nbsp;4,178,683 visitantes&nbsp;en los primeros 4 meses del a\u00f1o, lo que proyecta que este&nbsp;2024&nbsp;se supere la llegada de&nbsp;m\u00e1s de 11 millones de visitantes. As\u00ed lo inform\u00f3 este lunes el ministro de Turismo,&nbsp;David Collado, en su habitual&nbsp;conferencia de prensa, donde da a conocer el comportamiento de la&hellip;","_links":{"self":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/comments?post=4175"}],"version-history":[{"count":1,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4175\/revisions"}],"predecessor-version":[{"id":4177,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4175\/revisions\/4177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/media\/4176"}],"wp:attachment":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/media?parent=4175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/categories?post=4175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/tags?post=4175"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/series?post=4175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}