{"id":4160,"date":"2024-10-18T14:17:12","date_gmt":"2024-10-18T18:17:12","guid":{"rendered":"https:\/\/mayralapaz.com\/?p=4160"},"modified":"2024-10-18T14:17:13","modified_gmt":"2024-10-18T18:17:13","slug":"indotel-lanza-programa-que-promueve-uso-del-internet-seguro-en-ninos-ninas-y-adolescentes","status":"publish","type":"post","link":"https:\/\/mayralapaz.com\/index.php\/2024\/10\/18\/indotel-lanza-programa-que-promueve-uso-del-internet-seguro-en-ninos-ninas-y-adolescentes\/","title":{"rendered":"INDOTEL lanza programa que promueve uso del internet seguro en ni\u00f1os, ni\u00f1as y adolescentes"},"content":{"rendered":"\n<p>El Instituto Dominicano de las Telecomunicaciones (INDOTEL) lanz\u00f3 un programa educativo dirigido a fomentar el uso seguro del internet entre ni\u00f1os, ni\u00f1as y adolescentes, que inicia con la participaci\u00f3n de m\u00e1s de 100 estudiantes del Instituto Tecnol\u00f3gico Fabio Amable Mota.<\/p>\n\n\n\n<p>El programa, con una duraci\u00f3n de seis meses, est\u00e1 dirigido en esta primera etapa a adolescentes de entre 14 y 15 a\u00f1os, los cuales recibieron formaci\u00f3n sobre las mejores pr\u00e1cticas de seguridad en l\u00ednea y el uso responsable de herramientas tecnol\u00f3gicas clave.<\/p>\n\n\n\n<p>INDOTEL realizar\u00e1 10 talleres educativos entre octubre y noviembre, con la colaboraci\u00f3n de la franquicia Ciencia Divertida, que tiene como objetivo promover una cultura de ciberseguridad entre los j\u00f3venes dominicanos.<\/p>\n\n\n\n<p>Guido G\u00f3mez Mazara, presidente de INDOTEL, destac\u00f3 la importancia de este proyecto.<\/p>\n\n\n\n<p>\u201cEl internet es una herramienta poderosa, pero su uso debe ir acompa\u00f1ado de responsabilidad y precauci\u00f3n. Nuestro objetivo es preparar a los futuros ciudadanos y ciudadanas para que aprendan a protegerse en el entorno digital\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Patricia Solano, directora de Ciencia Divertida, expres\u00f3 su agradecimiento a INDOTEL por el apoyo en esta iniciativa.<\/p>\n\n\n\n<p>\u201cNos complace colaborar con una instituci\u00f3n tan comprometida con la educaci\u00f3n y la protecci\u00f3n de los j\u00f3venes. A trav\u00e9s de estos talleres, buscamos que los estudiantes no solo adquieran conocimientos, sino que desarrollen habilidades pr\u00e1cticas para navegar de manera segura en internet\u201d, indic\u00f3.<\/p>\n\n\n\n<p>Este tipo de programas permitir\u00e1 que los estudiantes no solo accedan al mundo digital, sino que conozcan las herramientas necesarias para proteger su privacidad y seguridad en l\u00ednea.<\/p>\n\n\n\n<p>En la actividad tambi\u00e9n participaron colaboradores del INDOTEL y docentes de la instituci\u00f3n educativa.<\/p>\n","protected":false},"excerpt":{"rendered":"El Instituto Dominicano de las Telecomunicaciones (INDOTEL) lanz\u00f3 un programa educativo dirigido a fomentar el uso seguro del internet entre ni\u00f1os, ni\u00f1as y adolescentes, que inicia con la participaci\u00f3n de m\u00e1s de 100 estudiantes del Instituto Tecnol\u00f3gico Fabio Amable Mota. El programa, con una duraci\u00f3n de seis meses, est\u00e1 dirigido en esta primera etapa a [&hellip;]","protected":false},"author":6,"featured_media":4161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","_joinchat":[],"footnotes":""},"categories":[35],"tags":[],"series":[],"class_list":["post-4160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa-rd"],"blocksy_meta":[],"episode_featured_image":"https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1.jpeg","episode_player_image":"https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1.jpeg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"light","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/mayralapaz.com\/feed\/podcast\/mayra-la-paz","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"u9gtatW8BQ\"><a href=\"https:\/\/mayralapaz.com\/index.php\/2024\/10\/18\/indotel-lanza-programa-que-promueve-uso-del-internet-seguro-en-ninos-ninas-y-adolescentes\/\">INDOTEL lanza programa que promueve uso del internet seguro en ni\u00f1os, ni\u00f1as y adolescentes<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/mayralapaz.com\/index.php\/2024\/10\/18\/indotel-lanza-programa-que-promueve-uso-del-internet-seguro-en-ninos-ninas-y-adolescentes\/embed\/#?secret=u9gtatW8BQ\" width=\"500\" height=\"350\" title=\"\u00abINDOTEL lanza programa que promueve uso del internet seguro en ni\u00f1os, ni\u00f1as y adolescentes\u00bb \u2014 Mayra La Paz\" data-secret=\"u9gtatW8BQ\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n<\/script>\n"},"uagb_featured_image_src":{"full":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1.jpeg",2560,1707,false],"thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-250x250.jpeg",250,250,true],"medium":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-300x200.jpeg",300,200,true],"medium_large":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-768x512.jpeg",768,512,true],"large":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-1024x683.jpeg",1024,683,true],"1536x1536":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-1536x1024.jpeg",1536,1024,true],"2048x2048":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-2048x1366.jpeg",2048,1366,true],"woocommerce_archive_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-500x500.jpeg",500,500,true],"woocommerce_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-300x300.jpeg",300,300,true],"woocommerce_single":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-600x400.jpeg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/10\/IMG_0607-scaled-1-100x100.jpeg",100,100,true]},"uagb_author_info":{"display_name":"Por la Redacci\u00f3n","author_link":"https:\/\/mayralapaz.com\/index.php\/author\/mayra\/"},"uagb_comment_info":0,"uagb_excerpt":"El Instituto Dominicano de las Telecomunicaciones (INDOTEL) lanz\u00f3 un programa educativo dirigido a fomentar el uso seguro del internet entre ni\u00f1os, ni\u00f1as y adolescentes, que inicia con la participaci\u00f3n de m\u00e1s de 100 estudiantes del Instituto Tecnol\u00f3gico Fabio Amable Mota. El programa, con una duraci\u00f3n de seis meses, est\u00e1 dirigido en esta primera etapa a&hellip;","_links":{"self":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/comments?post=4160"}],"version-history":[{"count":1,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4160\/revisions"}],"predecessor-version":[{"id":4162,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/4160\/revisions\/4162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/media\/4161"}],"wp:attachment":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/media?parent=4160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/categories?post=4160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/tags?post=4160"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/series?post=4160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}