{"id":3219,"date":"2024-10-01T20:57:19","date_gmt":"2024-10-02T00:57:19","guid":{"rendered":"https:\/\/mayralapaz.com\/?p=3219"},"modified":"2024-10-01T20:57:20","modified_gmt":"2024-10-02T00:57:20","slug":"guido-gomez-mazara-reafirma-su-compromiso-con-la-inclusion-laboral-en-indotel","status":"publish","type":"post","link":"https:\/\/mayralapaz.com\/index.php\/2024\/10\/01\/guido-gomez-mazara-reafirma-su-compromiso-con-la-inclusion-laboral-en-indotel\/","title":{"rendered":"Guido G\u00f3mez Mazara reafirma su compromiso con la inclusi\u00f3n laboral en INDOTEL"},"content":{"rendered":"\n<p>Santo Domingo. \u2014 El presidente del Consejo Directivo del Instituto Dominicano de las Telecomunicaciones (Indotel), Guido G\u00f3mez Mazara, dio la bienvenida al nuevo personal con discapacidad que se integra a diferentes direcciones de la instituci\u00f3n, ejecutando as\u00ed el compromiso asumido por ese \u00f3rgano del Estado con la creaci\u00f3n de un entorno laboral m\u00e1s inclusivo y equitativo.<\/p>\n\n\n\n<p>Las direcciones Jur\u00eddica, Tecnolog\u00eda y Atenci\u00f3n al Usuario integrar\u00e1n las personas con discapacidad, en cumplimiento con la inclusi\u00f3n laboral y la Ley 5-13 sobre discapacidad en el sector p\u00fablico.<\/p>\n\n\n\n<p>G\u00f3mez Mazara dijo que \u00abnos comprometemos a cumplir con el 5% de inserci\u00f3n laboral de personas con discapacidad y motivamos a otras instituciones del sector p\u00fablico a hacer lo mismo, garantizando el cumplimiento de esta ley. Nuestro objetivo es que todos se sientan c\u00f3modos, trabajando en un ambiente armonioso y lleno de oportunidades\u201d.<\/p>\n\n\n\n<p>El titular del Indotel manifest\u00f3 que en su gesti\u00f3n cree firmemente en la inclusi\u00f3n y que trabaja por un futuro equitativo para todos, al tiempo que resalt\u00f3 que seguir\u00e1n fortaleciendo la igualdad de derechos de personas con discapacidad hasta lograr el 5 por ciento que establece la ley.<\/p>\n\n\n\n<p>El no vidente Cristian Alexis P\u00e9rez Cuevas, quien es padre de dos ni\u00f1as, fue incorporado como abogado en la Direcci\u00f3n Jur\u00eddica de Indotel: \u00abagradezco la oportunidad que nos brinda esta instituci\u00f3n\u00bb, expres\u00f3 con emoci\u00f3n al poder integrarse al mercado laboral y asumir este nuevo reto, destacando que las limitaciones f\u00edsicas no definen el talento profesional.<\/p>\n\n\n\n<p>En la Direcci\u00f3n de Tecnolog\u00eda, Roberto Emilio B\u00e1ez Rosario, con una condici\u00f3n fisicomotora, se integra como auxiliar, donde desarrollar\u00e1 sus habilidades y destrezas en el \u00e1rea. B\u00e1ez Rosario, es un apasionado de la tecnolog\u00eda, su integraci\u00f3n refuerza el compromiso del Indotel con un espacio de trabajo inclusivo.<\/p>\n\n\n\n<p>Mientras que Julio C\u00e9sar Alm\u00e1nzar Agramonte, que padece de una condici\u00f3n fisicomotora, fue incorporado en la Direcci\u00f3n de Atenci\u00f3n al Usuario de Indotel. Almanzar manifest\u00f3 su agradecimiento: \u00abEs un honor formar parte de esta instituci\u00f3n. Esta oportunidad no solo me permite demostrar mis capacidades, sino tambi\u00e9n a sentirme \u00fatil y valorado, m\u00e1s all\u00e1 de mis limitaciones f\u00edsicas\u00bb.<\/p>\n\n\n\n<p>Esta iniciativa reafirma el compromiso de Indotel con la inclusi\u00f3n laboral y la igualdad de oportunidades, consolid\u00e1ndose como un referente en responsabilidad social y contribuyendo activamente al desarrollo sostenible y equitativo de Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p>G\u00f3mez Mazara se hizo acompa\u00f1ar de la directora ejecutiva de Indotel, Julissa Cruz, y el director de Gesti\u00f3n Humana, Juan Alberto Liranzo.<\/p>\n","protected":false},"excerpt":{"rendered":"Santo Domingo. \u2014 El presidente del Consejo Directivo del Instituto Dominicano de las Telecomunicaciones (Indotel), Guido G\u00f3mez Mazara, dio la bienvenida al nuevo personal con discapacidad que se integra a diferentes direcciones de la instituci\u00f3n, ejecutando as\u00ed el compromiso asumido por ese \u00f3rgano del Estado con la creaci\u00f3n de un entorno laboral m\u00e1s inclusivo y [&hellip;]","protected":false},"author":6,"featured_media":3206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","_joinchat":[],"footnotes":""},"categories":[35],"tags":[],"series":[],"class_list":["post-3219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa-rd"],"blocksy_meta":[],"episode_featured_image":"https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara.jpeg","episode_player_image":"https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara.jpeg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"light","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/mayralapaz.com\/feed\/podcast\/mayra-la-paz","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"RtwaAnfjuf\"><a href=\"https:\/\/mayralapaz.com\/index.php\/2024\/10\/01\/guido-gomez-mazara-reafirma-su-compromiso-con-la-inclusion-laboral-en-indotel\/\">Guido G\u00f3mez Mazara reafirma su compromiso con la inclusi\u00f3n laboral en INDOTEL<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/mayralapaz.com\/index.php\/2024\/10\/01\/guido-gomez-mazara-reafirma-su-compromiso-con-la-inclusion-laboral-en-indotel\/embed\/#?secret=RtwaAnfjuf\" width=\"500\" height=\"350\" title=\"\u00abGuido G\u00f3mez Mazara reafirma su compromiso con la inclusi\u00f3n laboral en INDOTEL\u00bb \u2014 Mayra La Paz\" data-secret=\"RtwaAnfjuf\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n<\/script>\n"},"uagb_featured_image_src":{"full":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara.jpeg",2560,1705,false],"thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-150x150.jpeg",150,150,true],"medium":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-300x200.jpeg",300,200,true],"medium_large":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-768x512.jpeg",768,512,true],"large":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-1024x682.jpeg",1024,682,true],"1536x1536":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-1536x1023.jpeg",1536,1023,true],"2048x2048":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-2048x1364.jpeg",2048,1364,true],"woocommerce_archive_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-500x500.jpeg",500,500,true],"woocommerce_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-300x300.jpeg",300,300,true],"woocommerce_single":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-600x400.jpeg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/mayralapaz.com\/wp-content\/uploads\/2024\/09\/Gomez-mazara-100x100.jpeg",100,100,true]},"uagb_author_info":{"display_name":"Por la Redacci\u00f3n","author_link":"https:\/\/mayralapaz.com\/index.php\/author\/mayra\/"},"uagb_comment_info":0,"uagb_excerpt":"Santo Domingo. \u2014 El presidente del Consejo Directivo del Instituto Dominicano de las Telecomunicaciones (Indotel), Guido G\u00f3mez Mazara, dio la bienvenida al nuevo personal con discapacidad que se integra a diferentes direcciones de la instituci\u00f3n, ejecutando as\u00ed el compromiso asumido por ese \u00f3rgano del Estado con la creaci\u00f3n de un entorno laboral m\u00e1s inclusivo y&hellip;","_links":{"self":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/3219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/comments?post=3219"}],"version-history":[{"count":1,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/3219\/revisions"}],"predecessor-version":[{"id":3220,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/posts\/3219\/revisions\/3220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/media\/3206"}],"wp:attachment":[{"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/media?parent=3219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/categories?post=3219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/tags?post=3219"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/mayralapaz.com\/index.php\/wp-json\/wp\/v2\/series?post=3219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}